{"id":108710,"date":"2025-03-27T00:20:06","date_gmt":"2025-03-26T23:20:06","guid":{"rendered":"https:\/\/asmcasas.com\/inmueble\/inmobiliaria-en-valencia-y-benicasim-alquila-piso-en-calle-juan-de-austria\/"},"modified":"2025-03-27T00:20:19","modified_gmt":"2025-03-26T23:20:19","slug":"inmobiliaria-en-valencia-y-benicasim-alquila-piso-en-calle-juan-de-austria","status":"publish","type":"property","link":"https:\/\/asmcasas.com\/en\/inmueble\/inmobiliaria-en-valencia-y-benicasim-alquila-piso-en-calle-juan-de-austria\/","title":{"rendered":"Inmobiliaria en Valencia y Benicasim alquila piso en calle Juan de Austria"},"content":{"rendered":"<p>Ref.: 02-15138 Asmcasas<\/p>\n<p> Excelente vivienda para ALQUILAR SIN MUEBLES  Y SIN ELECTRODOM\u00c9STICOS en el centro de la Ciudad. Vivienda de 110 metros distribuida en dos habitaciones dobles, ampl\u00edsimo  sal\u00f3n comedor con dos ambientes, cocina independiente y dos ba\u00f1os completos, uno con ducha y otro con ba\u00f1era, uno en suite. El inmueble cuenta con much\u00edsimos armarios empotrados distribuidos en toda la casa, en total 12. Split frio &#8211; calor en sal\u00f3n. Suelos de parquet , orientaci\u00f3n norte. Finca con conserje .<\/p>\n<p> Si quieres vivir en el centro de Valencia esta es tu vivienda ya que est\u00e1 en una de las calles m\u00e1s consolidadas y emblem\u00e1ticas de la ciudad. Ofrece todo tipo de comercios, incluso el Corte Ingles. A un paso de la Plaza del Ayuntamiento. Transporte p\u00fablico como autobuses EMT y parada de Metro en la misma puerta. <\/p>\n<p> El precio ofertado no incluye impuestos , gastos de compraventa ni honorarios de la agencia inmobiliaria.<\/p>\n<p> Anuncio no vinculante, puede contener errores.<\/p>\n<p> AsmCasas es una empresa que naci\u00f3 en 1999, formada por un equipo con  mucha experiencia en el sector inmobiliario. Nuestro objetivo es satisfacer las necesidades de nuestros clientes en la zona de Levante. Actualmente tenemos nuestra sede en Calle Jaime Roig n\u00ba 26 Bajo Valencia .Especializados en asesoramiento financiero y comercializaci\u00f3n de viviendas de obra nueva y segunda mano. Estamos logrando alcanzar un espacio de privilegio dentro del Sector Inmobiliario.<\/p>\n<p> Cubrimos todas las necesidades inmobiliarias: viviendas, oficinas, locales comerciales, solares, terrenos para construir\u2026 y cualquier tipo de operaciones: Compra-Venta y Alquiler.<\/p>\n<p> Desde el principio, la profesionalidad, la vocaci\u00f3n de servicio y la especializaci\u00f3n de la red comercial, se han convertido en los pilares b\u00e1sicos de la empresa y, gracias a ello, cientos de personas han confiado en AsmCasas.<\/p>\n<p> El asesoramiento comercial, nuestro estudio del mercado Gratuito, la adaptaci\u00f3n de la oferta a las necesidades del cliente, as\u00ed como el asesoramiento jur\u00eddico, fiscal y t\u00e9cnico son algunos de los servicios de AsmCasas que, gracias a sus departamentos especializados y a trav\u00e9s de la figura del asesor personal, le permiten conseguir su excelencia en el servicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ref.: 02-15138 Asmcasas Excelente vivienda para ALQUILAR SIN MUEBLES Y SIN ELECTRODOM\u00c9STICOS en el centro de la Ciudad. Vivienda de 110 metros distribuida en dos habitaciones dobles, ampl\u00edsimo sal\u00f3n comedor con dos ambientes, cocina independiente y dos ba\u00f1os completos, uno con ducha y otro con ba\u00f1era, uno en suite. El inmueble cuenta con much\u00edsimos armarios [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"template":"","property_type":[538],"property_status":[558],"property_feature":[544,545,577,548,543,540,559,546],"property_label":[553,550,551,652,564,552],"property_country":[554],"property_state":[555],"property_city":[556],"property_area":[765],"class_list":["post-108710","property","type-property","status-publish","hentry","property_type-piso","property_status-alquilar","property_feature-armarios-empotrados","property_feature-ascensor","property_feature-bomba-frio-calor","property_feature-calefaccion","property_feature-luminoso","property_feature-luz","property_feature-piscina","property_feature-puerta-blindada","property_label-acrilico","property_label-aluminio","property_label-entrar-a-vivir","property_label-norte","property_label-split-en-pared","property_label-terrazo","property_country-espana","property_state-valencia","property_city-valencia","property_area-sant-francesc"],"aioseo_notices":[],"property_meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":365,\"es\":365}}"],"_wp_page_template":["default"],"_icl_lang_duplicate_of":["97832"],"houzez_geolocation_lat":["39.470250674492"],"houzez_geolocation_long":["-0.371498647321827"],"houzez_total_property_views":["148"],"houzez_views_by_date":["a:61:{s:10:\"10-19-2025\";i:1;s:10:\"10-20-2025\";i:1;s:10:\"10-25-2025\";i:1;s:10:\"10-31-2025\";i:1;s:10:\"11-15-2025\";i:1;s:10:\"11-17-2025\";i:4;s:10:\"11-22-2025\";i:1;s:10:\"11-24-2025\";i:1;s:10:\"11-27-2025\";i:1;s:10:\"11-29-2025\";i:2;s:10:\"12-03-2025\";i:1;s:10:\"12-11-2025\";i:1;s:10:\"12-18-2025\";i:1;s:10:\"12-19-2025\";i:1;s:10:\"12-21-2025\";i:1;s:10:\"12-22-2025\";i:1;s:10:\"12-24-2025\";i:1;s:10:\"12-27-2025\";i:1;s:10:\"01-13-2026\";i:1;s:10:\"01-16-2026\";i:1;s:10:\"01-27-2026\";i:2;s:10:\"01-29-2026\";i:1;s:10:\"02-01-2026\";i:1;s:10:\"02-12-2026\";i:1;s:10:\"02-15-2026\";i:1;s:10:\"02-17-2026\";i:1;s:10:\"02-21-2026\";i:2;s:10:\"02-25-2026\";i:1;s:10:\"02-27-2026\";i:1;s:10:\"03-03-2026\";i:1;s:10:\"03-04-2026\";i:1;s:10:\"03-12-2026\";i:2;s:10:\"03-18-2026\";i:1;s:10:\"03-20-2026\";i:1;s:10:\"03-25-2026\";i:1;s:10:\"04-01-2026\";i:1;s:10:\"04-05-2026\";i:1;s:10:\"04-15-2026\";i:1;s:10:\"04-17-2026\";i:1;s:10:\"04-23-2026\";i:1;s:10:\"05-02-2026\";i:1;s:10:\"05-06-2026\";i:1;s:10:\"05-14-2026\";i:1;s:10:\"05-19-2026\";i:1;s:10:\"05-20-2026\";i:1;s:10:\"05-21-2026\";i:1;s:10:\"05-22-2026\";i:1;s:10:\"05-24-2026\";i:1;s:10:\"05-31-2026\";i:1;s:10:\"06-04-2026\";i:1;s:10:\"06-05-2026\";i:1;s:10:\"06-07-2026\";i:1;s:10:\"06-12-2026\";i:1;s:10:\"06-20-2026\";i:1;s:10:\"06-25-2026\";i:1;s:10:\"06-26-2026\";i:2;s:10:\"07-01-2026\";i:1;s:10:\"07-02-2026\";i:1;s:10:\"07-04-2026\";i:1;s:10:\"07-10-2026\";i:1;s:10:\"07-14-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-14 04:11:27"],"image_to_attach":["104556,104558,104560,104562,104564,104566,104568,104570,104572,104574,104576,104578,104580,104582,104584,104586,104588,104590,104592,104594"],"wp_schema_pro_optimized_structured_data":["<!-- Schema optimized by Schema Pro --><!-- \/ Schema optimized by Schema Pro -->"],"fave_currency":["EUR"],"fave_currency_info":["a:8:{s:2:\"id\";s:1:\"1\";s:13:\"currency_name\";s:4:\"Euro\";s:13:\"currency_code\";s:3:\"EUR\";s:15:\"currency_symbol\";s:3:\"\u20ac\";s:17:\"currency_position\";s:5:\"after\";s:16:\"currency_decimal\";s:1:\"2\";s:26:\"currency_decimal_separator\";s:1:\",\";s:27:\"currency_thousand_separator\";s:1:\".\";}"],"fave_property_country":["ES"],"fave_floor_plans_enable":["disable"],"fave_additional_features_enable":["disable"],"fave_multiunit_plans_enable":["disable"],"floor_plans":[""],"fave_multi_units":[""],"additional_features":[""],"_last_translation_edit_mode":["translation-editor"],"_wpml_media_has_media":["1"],"uniquekey":["6588586"],"fave_property_price":["950"],"fave_property_size":["110.00"],"fave_property_land":["0"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["2"],"fave_property_map":["1"],"fave_property_id":["02-15138"],"fave_property_year":["1982"],"fave_property_zip":["46002"],"fave_featured":["0"],"fave_agent_display_option":["agent_info"],"fave_prop_homeslider":["no"],"fave_agents":["16589"],"fave_property_map_address":[""],"fave_property_location":["39.470250674492,-0.371498647321827"],"fave_property_images":["104556","104558","104560","104562","104564","104566","104568","104570","104572","104574","104576","104578","104580","104582","104584","104586","104588","104590","104592","104594"]},"_links":{"self":[{"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/properties\/108710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/types\/property"}],"version-history":[{"count":1,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/properties\/108710\/revisions"}],"predecessor-version":[{"id":110153,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/properties\/108710\/revisions\/110153"}],"wp:attachment":[{"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/media?parent=108710"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_type?post=108710"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_status?post=108710"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_feature?post=108710"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_label?post=108710"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_country?post=108710"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_state?post=108710"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_city?post=108710"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/asmcasas.com\/en\/wp-json\/wp\/v2\/property_area?post=108710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}